{"id":7054,"date":"2025-05-14T18:00:38","date_gmt":"2025-05-14T18:00:38","guid":{"rendered":"https:\/\/britishswimschool.com\/torontowest-etobicoke\/program\/caballito-de-mar\/"},"modified":"2026-07-15T02:28:33","modified_gmt":"2026-07-15T02:28:33","slug":"caballito-de-mar","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/torontowest-etobicoke\/es\/programs\/caballito-de-mar\/","title":{"rendered":"Seahorse"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Para ni\u00f1os peque\u00f1os de 18 a 36 meses que est\u00e1n listos para aprender solo con el apoyo de un instructor<\/h3>\n\n<p>Seahorse es un programa independiente introductorio para ni\u00f1os peque\u00f1os que est\u00e1n listos para sentarse en el borde de la piscina de forma independiente y han desarrollado las habilidades b\u00e1sicas introducidas en niveles anteriores. Los padres permanecen cerca, justo detr\u00e1s del nadador en el agua, para brindar comodidad mientras permiten que su hijo tome m\u00e1s iniciativa durante las clases. Los instructores trabajan directamente con cada nadador para desarrollar las t\u00e9cnicas de supervivencia introducidas anteriormente, ofreciendo orientaci\u00f3n personalizada en un entorno divertido y de ritmo r\u00e1pido que fomenta la confianza y el progreso continuo.<\/p>\n\n<h4 class=\"wp-block-heading\">5 objetivos de seahorse<\/h4>\n\n<ol class=\"wp-block-list\">\n<li>Flotaci\u00f3n de espaldas independiente<\/li>\n\n\n\n<li>Volteo y flotaci\u00f3n subacu\u00e1ticos independientes<\/li>\n\n\n\n<li>Impulso desde la pared y volteo<\/li>\n\n\n\n<li>Saltar, darse la vuelta y flotar durante 20 segundos de forma independiente<\/li>\n\n\n\n<li>Independencia de los padres<\/li>\n<\/ol>\n\n<p><\/p>\n","protected":false},"featured_media":6090,"template":"","meta":{"_acf_changed":false},"class_list":["post-7054","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/torontowest-etobicoke\/es\/wp-json\/wp\/v2\/program\/7054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/torontowest-etobicoke\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/torontowest-etobicoke\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":2,"href":"https:\/\/britishswimschool.com\/torontowest-etobicoke\/es\/wp-json\/wp\/v2\/program\/7054\/revisions"}],"predecessor-version":[{"id":8772,"href":"https:\/\/britishswimschool.com\/torontowest-etobicoke\/es\/wp-json\/wp\/v2\/program\/7054\/revisions\/8772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/torontowest-etobicoke\/es\/wp-json\/wp\/v2\/media\/6090"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/torontowest-etobicoke\/es\/wp-json\/wp\/v2\/media?parent=7054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}