{"id":7056,"date":"2025-05-14T18:06:29","date_gmt":"2025-05-14T18:06:29","guid":{"rendered":"https:\/\/britishswimschool.com\/summerville\/program\/tortuga-2\/"},"modified":"2026-07-15T02:03:22","modified_gmt":"2026-07-15T02:03:22","slug":"tortuga-2","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/summerville\/es\/programs\/tortuga-2\/","title":{"rendered":"Turtle 2"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Para ni\u00f1os a partir de 3 a\u00f1os que est\u00e9n listos para avanzar en el desarrollo de sus brazadas y resistencia<\/h3>\n\n<p>Turtle 2 marca el comienzo del viaje del \u201cnadador m\u00e1s fuerte\u201d. Despu\u00e9s de graduarse del programa de \u201cnadador m\u00e1s seguro\u201d, los nadadores est\u00e1n listos para desarrollar resistencia, refinar la t\u00e9cnica y aumentar su tiempo en el agua. Este nivel se centra en fortalecer el estilo libre, el estilo espalda y el estilo braza, al tiempo que se introduce la patada de mariposa. Los nadadores rotan a trav\u00e9s de ejercicios espec\u00edficos de cada estilo, trabajan junto a sus compa\u00f1eros y aprenden a trav\u00e9s de la observaci\u00f3n, el entrenamiento y la repetici\u00f3n. Con un \u00e9nfasis continuo en las habilidades de seguridad en el agua, como el braceo, las lecciones est\u00e1n dise\u00f1adas para desafiar a cada nadador a su nivel individual, apoyando tanto la confianza como el progreso a largo plazo.<\/p>\n\n<h4 class=\"wp-block-heading\">5 objetivos de tortuga 2<\/h4>\n\n<ol class=\"wp-block-list\">\n<li>Espalda 20 yardas<\/li>\n\n\n\n<li>Estilo libre 20 yardas<\/li>\n\n\n\n<li>Braza reconocible 10 yardas<\/li>\n\n\n\n<li>Demostrar patada de mariposa 10 yardas<\/li>\n\n\n\n<li>Mantenerse a flote durante 1 minuto<\/li>\n<\/ol>\n\n<p><\/p>\n","protected":false},"featured_media":6155,"template":"","meta":{"_acf_changed":false},"class_list":["post-7056","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/summerville\/es\/wp-json\/wp\/v2\/program\/7056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/summerville\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/summerville\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":2,"href":"https:\/\/britishswimschool.com\/summerville\/es\/wp-json\/wp\/v2\/program\/7056\/revisions"}],"predecessor-version":[{"id":8743,"href":"https:\/\/britishswimschool.com\/summerville\/es\/wp-json\/wp\/v2\/program\/7056\/revisions\/8743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/summerville\/es\/wp-json\/wp\/v2\/media\/6155"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/summerville\/es\/wp-json\/wp\/v2\/media?parent=7056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}