{"id":7061,"date":"2025-07-21T19:26:18","date_gmt":"2025-07-21T19:26:18","guid":{"rendered":"https:\/\/britishswimschool.com\/spacecoast\/program\/adulto\/"},"modified":"2026-07-15T02:12:26","modified_gmt":"2026-07-15T02:12:26","slug":"adulto","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/spacecoast\/es\/programs\/adulto\/","title":{"rendered":"Adulto"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Para nadadores mayores de 18 a\u00f1os con cualquier nivel de experiencia<\/h3>\n\n<p>Nuestro programa para adultos est\u00e1 dirigido por instructores especialmente capacitados para apoyar a estudiantes adultos de todos los niveles de experiencia, ya sea que est\u00e9s superando el miedo, desarrollando habilidades b\u00e1sicas o entrenando para un objetivo espec\u00edfico como un triatl\u00f3n. Las clases se imparten en un ambiente de apoyo y sin prejuicios, donde los nadadores son recibidos exactamente donde est\u00e1n. Si bien las sesiones incluyen actividades grupales, los instructores adaptan la gu\u00eda a los objetivos individuales de cada nadador, ofreciendo entrenamiento personalizado y un ritmo adaptado. Este programa est\u00e1 dise\u00f1ado para desarrollar confianza, competencia y comodidad en el agua, a tu manera y a tu ritmo.<\/p>\n\n<h4 class=\"wp-block-heading\">Estructura del programa<\/h4>\n\n<p><strong>Nivel 1:<\/strong> adaptaci\u00f3n al agua<\/p>\n\n<p><strong>Nivel 2:<\/strong> supervivencia en el agua<\/p>\n\n<p><strong>Nivel 3:<\/strong> desarrollo de brazadas<\/p>\n\n<p><\/p>\n","protected":false},"featured_media":6063,"template":"","meta":{"_acf_changed":false},"class_list":["post-7061","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/spacecoast\/es\/wp-json\/wp\/v2\/program\/7061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/spacecoast\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/spacecoast\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":2,"href":"https:\/\/britishswimschool.com\/spacecoast\/es\/wp-json\/wp\/v2\/program\/7061\/revisions"}],"predecessor-version":[{"id":8816,"href":"https:\/\/britishswimschool.com\/spacecoast\/es\/wp-json\/wp\/v2\/program\/7061\/revisions\/8816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/spacecoast\/es\/wp-json\/wp\/v2\/media\/6063"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/spacecoast\/es\/wp-json\/wp\/v2\/media?parent=7061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}