{"id":7671,"date":"2025-05-14T18:05:55","date_gmt":"2025-05-14T18:05:55","guid":{"rendered":"https:\/\/britishswimschool.com\/seattle\/program\/turtle-1\/"},"modified":"2026-07-15T02:00:45","modified_gmt":"2026-07-15T02:00:45","slug":"turtle-1","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/seattle\/es\/programs\/turtle-1\/","title":{"rendered":"Turtle 1"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Para ni\u00f1os a partir de 3 a\u00f1os que se sientan c\u00f3modos en el agua y est\u00e9n listos para desarrollar t\u00e9cnicas de brazada y seguridad<\/h3>\n\n<p>Tortuga 1 es el nivel final en nuestra progresi\u00f3n de nataci\u00f3n de supervivencia y marca un hito importante en el viaje de cada nadador. En este nivel, los nadadores aprenden los fundamentos clave de la brazada, incluyendo el estilo libre, el estilo espalda y una introducci\u00f3n al estilo braza, mientras contin\u00faan reforzando las habilidades b\u00e1sicas de supervivencia como nadar-girar-nadar y flotar de forma independiente. Las clases combinan resistencia, t\u00e9cnica y seguridad en el agua, y los instructores se centran tanto en las necesidades individuales como en la progresi\u00f3n del grupo. Al graduarse, los nadadores son reconocidos como \u201cnadadores m\u00e1s seguros\u201d y est\u00e1n listos para cambiar el enfoque hacia convertirse en nadadores m\u00e1s fuertes y h\u00e1biles en los siguientes niveles.   <\/p>\n\n<h4 class=\"wp-block-heading\">5 objetivos de tortuga 1<\/h4>\n\n<ol class=\"wp-block-list\">\n<li>Deslizarse con patada de aleteo de forma independiente<\/li>\n\n\n\n<li>Nadar-girar-nadar hasta un lugar seguro<\/li>\n\n\n\n<li>Nadar de forma independiente 10 yardas o 10 ciclos de estilo espalda para principiantes con los brazos extendidos<\/li>\n\n\n\n<li>Nadar de forma independiente 10 yardas o 10 ciclos de estilo libre para principiantes con los brazos extendidos<\/li>\n\n\n\n<li>Demostrar la respiraci\u00f3n lateral<\/li>\n<\/ol>\n\n<p><\/p>\n","protected":false},"featured_media":6146,"template":"","meta":{"_acf_changed":false},"class_list":["post-7671","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/program\/7671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":3,"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/program\/7671\/revisions"}],"predecessor-version":[{"id":9160,"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/program\/7671\/revisions\/9160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/media\/6146"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/media?parent=7671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}