{"id":7051,"date":"2025-05-14T18:04:48","date_gmt":"2025-05-14T18:04:48","guid":{"rendered":"https:\/\/britishswimschool.com\/seattle\/program\/estrella-de-mar\/"},"modified":"2026-07-15T02:00:45","modified_gmt":"2026-07-15T02:00:45","slug":"estrella-de-mar","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/seattle\/es\/programs\/estrella-de-mar\/","title":{"rendered":"Starfish"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Para ni\u00f1os a partir de 3 a\u00f1os que se inician en la nataci\u00f3n<\/h3>\n\n<p>Starfish est\u00e1 dise\u00f1ado para nadadores de 3 a\u00f1os en adelante que se inician en el agua, se sienten nerviosos o simplemente necesitan construir una comprensi\u00f3n b\u00e1sica de la seguridad y la supervivencia en el agua. Ya sean indecisos o entusiastas, los nadadores de este nivel aprenden a respetar y responder al agua a trav\u00e9s de la instrucci\u00f3n guiada, la observaci\u00f3n y el trabajo en equipo. Nuestros instructores capacitados se adaptan a cada ni\u00f1o, utilizando m\u00e9todos apropiados para su edad con el fin de generar confianza y comodidad. Las clases se centran en habilidades de supervivencia esenciales, como flotar de espaldas y la inmersi\u00f3n total, preparando a los nadadores para niveles m\u00e1s avanzados.   <\/p>\n\n<h4 class=\"wp-block-heading\">5 objetivos de Starfish<\/h4>\n\n<ol class=\"wp-block-list\">\n<li>Aclimataci\u00f3n al agua<\/li>\n\n\n\n<li>Sin l\u00e1grimas, sin miedo<\/li>\n\n\n\n<li>Flotaci\u00f3n de espaldas independiente<\/li>\n\n\n\n<li>Salto independiente desde la pared con inmersi\u00f3n<\/li>\n\n\n\n<li>Independencia en el flotador <\/li>\n<\/ol>\n\n<p><\/p>\n","protected":false},"featured_media":6128,"template":"","meta":{"_acf_changed":false},"class_list":["post-7051","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/program\/7051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":3,"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/program\/7051\/revisions"}],"predecessor-version":[{"id":9154,"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/program\/7051\/revisions\/9154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/media\/6128"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/seattle\/es\/wp-json\/wp\/v2\/media?parent=7051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}