{"id":7062,"date":"2025-07-21T23:02:24","date_gmt":"2025-07-21T23:02:24","guid":{"rendered":"https:\/\/britishswimschool.com\/san-diego-temecula-valley\/program\/delfin\/"},"modified":"2026-07-14T02:00:16","modified_gmt":"2026-07-14T02:00:16","slug":"delfin","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/san-diego-temecula-valley\/es\/programs\/delfin\/","title":{"rendered":"Dolphin"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Para nadadores con capacidades especiales<\/h3>\n\n<p>Dolphin es nuestro programa de nataci\u00f3n adaptada, cuidadosamente dise\u00f1ado para nadadores de todas las edades con diferencias de desarrollo, sensoriales o f\u00edsicas. Los instructores reciben una formaci\u00f3n especializada centrada en la empat\u00eda, el desarrollo infantil y las t\u00e9cnicas de nataci\u00f3n adaptada para garantizar que cada nadador reciba el apoyo que necesita. Cada lecci\u00f3n se adapta al individuo, reuni\u00e9ndose con \u00e9l donde est\u00e1 y aprovechando sus puntos fuertes \u00fanicos. Con un enfoque en la comodidad, la comunicaci\u00f3n y la seguridad acu\u00e1tica fundamental, este programa proporciona un entorno acogedor y comprensivo donde cada nadador puede aprender y prosperar a su propio ritmo.<\/p>\n\n<p>Las proporciones de instructor por alumno var\u00edan en funci\u00f3n de las necesidades individuales de cada nadador para garantizar el entorno de aprendizaje m\u00e1s seguro y de mayor apoyo.<\/p>\n\n<p><\/p>\n","protected":false},"featured_media":6072,"template":"","meta":{"_acf_changed":false},"class_list":["post-7062","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/san-diego-temecula-valley\/es\/wp-json\/wp\/v2\/program\/7062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/san-diego-temecula-valley\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/san-diego-temecula-valley\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":2,"href":"https:\/\/britishswimschool.com\/san-diego-temecula-valley\/es\/wp-json\/wp\/v2\/program\/7062\/revisions"}],"predecessor-version":[{"id":8787,"href":"https:\/\/britishswimschool.com\/san-diego-temecula-valley\/es\/wp-json\/wp\/v2\/program\/7062\/revisions\/8787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/san-diego-temecula-valley\/es\/wp-json\/wp\/v2\/media\/6072"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/san-diego-temecula-valley\/es\/wp-json\/wp\/v2\/media?parent=7062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}