{"id":7059,"date":"2025-05-14T17:52:26","date_gmt":"2025-05-14T17:52:26","guid":{"rendered":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/program\/renacuajo\/"},"modified":"2026-09-02T02:28:39","modified_gmt":"2026-09-02T02:28:39","slug":"renacuajo","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/programs\/renacuajo\/","title":{"rendered":"Tadpole"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Tadpole: clases de nataci\u00f3n para beb\u00e9s y ni\u00f1os peque\u00f1os de 3 a 36 meses<\/h3>\n\n<p>Tadpole es una clase de nataci\u00f3n para padres e hijos, dirigida a beb\u00e9s y ni\u00f1os peque\u00f1os de 3 a 36 meses, que se realiza con un padre, madre o tutor en el agua en cada sesi\u00f3n. Este programa introduce a los m\u00e1s peque\u00f1os al agua en un entorno tranquilo y divertido, dise\u00f1ado para fomentar la comodidad y la confianza. Con un padre\/tutor en la piscina, nuestros instructores capacitados dirigen el grupo utilizando canciones, juegos y movimientos suaves para fomentar una conexi\u00f3n positiva con el agua. Cada lecci\u00f3n se centra en la aclimataci\u00f3n, el fomento de la confianza y la introducci\u00f3n de habilidades b\u00e1sicas que comienzan a desarrollar la memoria muscular para futuros progresos. Los padres tambi\u00e9n reciben consejos \u00fatiles e informaci\u00f3n sobre la concienciaci\u00f3n y la supervisi\u00f3n en el agua durante toda la clase.    <\/p>\n\n<h4 class=\"wp-block-heading\">5 objetivos de Tadpole<\/h4>\n\n<ol class=\"wp-block-list\">\n<li>Aclimataci\u00f3n al agua<\/li>\n\n\n\n<li>Sin l\u00e1grimas, sin miedo<\/li>\n\n\n\n<li>Flotaci\u00f3n dorsal asistida con las orejas dentro del agua<\/li>\n\n\n\n<li>Inmersi\u00f3n suave completa<\/li>\n\n\n\n<li>Avanzando hacia la independencia en el flotador<\/li>\n<\/ol>\n\n<p><\/p>\n","protected":false},"featured_media":6112,"template":"","meta":{"_acf_changed":false},"class_list":["post-7059","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/program\/7059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":4,"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/program\/7059\/revisions"}],"predecessor-version":[{"id":9121,"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/program\/7059\/revisions\/9121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/media\/6112"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/media?parent=7059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}