{"id":7058,"date":"2025-05-14T18:00:06","date_gmt":"2025-05-14T18:00:06","guid":{"rendered":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/program\/swimboree\/"},"modified":"2026-09-02T02:28:39","modified_gmt":"2026-09-02T02:28:39","slug":"swimboree","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/programs\/swimboree\/","title":{"rendered":"Swimboree"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Swimboree: clases de nataci\u00f3n para beb\u00e9s y ni\u00f1os peque\u00f1os de 3 a 36 meses (graduados de renacuajo)<\/h3>\n\n<p>Swimboree es la clase de nataci\u00f3n de nivel avanzado para beb\u00e9s y ni\u00f1os peque\u00f1os de 3 a 36 meses que han completado renacuajo, con un tama\u00f1o de grupo m\u00e1s peque\u00f1o que permite a los instructores trabajar de manera pr\u00e1ctica con cada nadador. Este programa se basa en la aclimataci\u00f3n y la comodidad en el agua adquiridas en el nivel de renacuajo, con un tama\u00f1o de clase m\u00e1s peque\u00f1o para permitir que los instructores trabajen de manera m\u00e1s cercana y pr\u00e1ctica con cada nadador. Los padres\/tutores permanecen en el agua para brindar tranquilidad, mientras que los instructores introducen t\u00e9cnicas tempranas de nataci\u00f3n de supervivencia utilizando canciones, movimientos intencionados y actividades atractivas. Esta clase ayuda a los nadadores a tener m\u00e1s confianza y comenzar a desarrollar independencia en el agua, sirviendo como un puente entre la participaci\u00f3n total de los padres\/tutores y la futura instrucci\u00f3n independiente.   <\/p>\n\n<h4 class=\"wp-block-heading\">5 objetivos de swimboree<\/h4>\n\n<ol class=\"wp-block-list\">\n<li>Flotaci\u00f3n dorsal asistida (o independiente)<\/li>\n\n\n\n<li>Giro sumergido asistido (o independiente)<\/li>\n\n\n\n<li>Inmersi\u00f3n total desde la pared (sentado o de pie)<\/li>\n\n\n\n<li>Capaz de separarse del padre\/madre<\/li>\n\n\n\n<li>Independiente en el flotador<\/li>\n<\/ol>\n\n<p><\/p>\n","protected":false},"featured_media":6121,"template":"","meta":{"_acf_changed":false},"class_list":["post-7058","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/program\/7058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":4,"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/program\/7058\/revisions"}],"predecessor-version":[{"id":9129,"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/program\/7058\/revisions\/9129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/media\/6121"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/roanoke-lynchburg\/es\/wp-json\/wp\/v2\/media?parent=7058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}