{"id":7055,"date":"2025-05-14T18:14:56","date_gmt":"2025-05-14T18:14:56","guid":{"rendered":"https:\/\/britishswimschool.com\/metro-charlotte\/program\/tiburon-2\/"},"modified":"2026-07-14T02:00:46","modified_gmt":"2026-07-14T02:00:46","slug":"tiburon-2","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/metro-charlotte\/es\/programs\/tiburon-2\/","title":{"rendered":"Shark 2"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Para nadadores avanzados que se preparan para el equipo de nataci\u00f3n, para desarrollar resistencia y rendimiento<\/h3>\n\n<p>Shark 2 es el nivel final del programa principal de British Swim School, dise\u00f1ado para nadadores avanzados que est\u00e1n listos para perfeccionar su t\u00e9cnica y rendimiento. Las clases se centran en perfeccionar la mec\u00e1nica de los estilos, los patrones de respiraci\u00f3n, la posici\u00f3n del cuerpo y habilidades avanzadas como transiciones, virajes de volteo y salidas de estilo de competici\u00f3n. Con \u00e9nfasis en la resistencia y la eficiencia, los nadadores trabajan para alcanzar objetivos de distancia de 50 yardas en cada estilo. La graduaci\u00f3n de este nivel marca la finalizaci\u00f3n exitosa del programa de British Swim School, equipando a los nadadores con las habilidades y la confianza para unirse a un equipo de nataci\u00f3n o continuar nadando recreativamente con fuerza y control.   <\/p>\n\n<h4 class=\"wp-block-heading\">5 objetivos de Tibur\u00f3n 2<\/h4>\n\n<ol class=\"wp-block-list\">\n<li>50 yardas de espalda<\/li>\n\n\n\n<li>50 yardas de estilo libre<\/li>\n\n\n\n<li>50 yardas de braza<\/li>\n\n\n\n<li>50 yardas de mariposa<\/li>\n\n\n\n<li>Salidas y virajes para cada estilo<\/li>\n<\/ol>\n\n<p><\/p>\n","protected":false},"featured_media":6106,"template":"","meta":{"_acf_changed":false},"class_list":["post-7055","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/metro-charlotte\/es\/wp-json\/wp\/v2\/program\/7055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/metro-charlotte\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/metro-charlotte\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":4,"href":"https:\/\/britishswimschool.com\/metro-charlotte\/es\/wp-json\/wp\/v2\/program\/7055\/revisions"}],"predecessor-version":[{"id":9155,"href":"https:\/\/britishswimschool.com\/metro-charlotte\/es\/wp-json\/wp\/v2\/program\/7055\/revisions\/9155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/metro-charlotte\/es\/wp-json\/wp\/v2\/media\/6106"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/metro-charlotte\/es\/wp-json\/wp\/v2\/media?parent=7055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}