{"id":7050,"date":"2025-05-14T18:05:27","date_gmt":"2025-05-14T18:05:27","guid":{"rendered":"https:\/\/britishswimschool.com\/greater-santa-clara\/program\/pez-pequeno\/"},"modified":"2026-07-15T02:08:11","modified_gmt":"2026-07-15T02:08:11","slug":"pez-pequeno","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/greater-santa-clara\/es\/programs\/pez-pequeno\/","title":{"rendered":"Minnow"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Para ni\u00f1os a partir de 3 a\u00f1os que est\u00e9n listos para empezar a aprender habilidades de supervivencia en el agua<\/h3>\n\n<p>Minnow es un nivel centrado en la supervivencia donde los nadadores participan en una clase completa de 30 minutos dedicada a practicar t\u00e9cnicas esenciales de auto rescate. Las habilidades clave incluyen flotar de espaldas, darse la vuelta despu\u00e9s de la inmersi\u00f3n y regresar de forma segura a la pared. Aunque se ense\u00f1a en un entorno grupal, los instructores brindan atenci\u00f3n individualizada durante el turno de cada nadador, adaptando la instrucci\u00f3n a su punto espec\u00edfico en la progresi\u00f3n. Las lecciones son atractivas pero decididas, construyendo confianza en el agua, control corporal y la independencia necesaria para la seguridad acu\u00e1tica en el mundo real.   <\/p>\n\n<h4 class=\"wp-block-heading\">5 objetivos de Minnow<\/h4>\n\n<ol class=\"wp-block-list\">\n<li>Entrada segura\/salida segura<\/li>\n\n\n\n<li>Saltar, darse la vuelta y flotar durante 20 segundos de forma independiente<\/li>\n\n\n\n<li>Deslizamiento independiente de regreso a la pared<\/li>\n\n\n\n<li>Estilo espalda elemental durante 10 ciclos<\/li>\n\n\n\n<li>Comienzo de pez espada, empujar el deslizamiento desde la pared hacia un vuelco. Flotar de espaldas durante 20 segundos. <\/li>\n<\/ol>\n\n<p><\/p>\n","protected":false},"featured_media":6081,"template":"","meta":{"_acf_changed":false},"class_list":["post-7050","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/greater-santa-clara\/es\/wp-json\/wp\/v2\/program\/7050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/greater-santa-clara\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/greater-santa-clara\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":3,"href":"https:\/\/britishswimschool.com\/greater-santa-clara\/es\/wp-json\/wp\/v2\/program\/7050\/revisions"}],"predecessor-version":[{"id":8875,"href":"https:\/\/britishswimschool.com\/greater-santa-clara\/es\/wp-json\/wp\/v2\/program\/7050\/revisions\/8875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/greater-santa-clara\/es\/wp-json\/wp\/v2\/media\/6081"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/greater-santa-clara\/es\/wp-json\/wp\/v2\/media?parent=7050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}