{"id":7060,"date":"2025-07-21T20:13:33","date_gmt":"2025-07-21T20:13:33","guid":{"rendered":"https:\/\/britishswimschool.com\/glendale-burbank\/program\/adulto-joven\/"},"modified":"2026-07-15T02:04:49","modified_gmt":"2026-07-15T02:04:49","slug":"adulto-joven","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/programs\/adulto-joven\/","title":{"rendered":"Adulto joven"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Para nadadores de 12 a 17 a\u00f1os de cualquier nivel de experiencia<\/h3>\n\n<p>Nuestro programa para j\u00f3venes ofrece una experiencia enriquecedora e inclusiva para nadadores j\u00f3venes que se inician en el agua o que desean fortalecer sus habilidades. Dise\u00f1ado para adaptarse a cada nadador dondequiera que est\u00e9, este programa introduce t\u00e9cnicas esenciales de nataci\u00f3n y conceptos de seguridad acu\u00e1tica en un entorno de apoyo y sin prejuicios. Agrupados por edad y habilidad, los nadadores se benefician de una instrucci\u00f3n personalizada, una conexi\u00f3n positiva con sus compa\u00f1eros y un enfoque en el desarrollo de la confianza, la comodidad y las habilidades para toda la vida, a su propio ritmo y a su manera.  <\/p>\n\n<h4 class=\"wp-block-heading\">Estructura del programa<\/h4>\n\n<p><strong>Nivel 1:<\/strong> adaptaci\u00f3n al agua<\/p>\n\n<p><strong>Nivel 2:<\/strong> supervivencia en el agua<\/p>\n\n<p><strong>Nivel 3:<\/strong> desarrollo de brazadas<\/p>\n\n<p><\/p>\n","protected":false},"featured_media":6137,"template":"","meta":{"_acf_changed":false},"class_list":["post-7060","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/program\/7060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":5,"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/program\/7060\/revisions"}],"predecessor-version":[{"id":8908,"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/program\/7060\/revisions\/8908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/media\/6137"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/media?parent=7060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}