{"id":7053,"date":"2025-05-14T18:14:30","date_gmt":"2025-05-14T18:14:30","guid":{"rendered":"https:\/\/britishswimschool.com\/glendale-burbank\/program\/tiburon-1\/"},"modified":"2026-07-15T02:04:50","modified_gmt":"2026-07-15T02:04:50","slug":"tiburon-1","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/programs\/tiburon-1\/","title":{"rendered":"Shark 1"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Para ni\u00f1os a partir de 3 a\u00f1os que est\u00e9n perfeccionando la t\u00e9cnica en los cuatro estilos<\/h3>\n\n<p>Tibur\u00f3n 1 es un nivel avanzado dise\u00f1ado para nadadores que han desarrollado unos fundamentos s\u00f3lidos en los estilos y una buena posici\u00f3n corporal. Partiendo de esta base, las clases se centran en perfeccionar la t\u00e9cnica, mejorar el control de la respiraci\u00f3n y aumentar la resistencia y la fuerza en los cuatro estilos: crol, espalda, braza y mariposa. Se introduce la nataci\u00f3n de distancia, junto con habilidades avanzadas como los virajes de volteo y la posici\u00f3n hidrodin\u00e1mica. Se anima a los nadadores a ser m\u00e1s independientes y a orientarse a los objetivos, centr\u00e1ndose en el crecimiento personal, la constancia y la preparaci\u00f3n para la nataci\u00f3n de nivel superior.   <\/p>\n\n<h4 class=\"wp-block-heading\">5 objetivos de Tibur\u00f3n 1<\/h4>\n\n<ol class=\"wp-block-list\">\n<li>Espalda 25 yardas<\/li>\n\n\n\n<li>Crol 25 yardas<\/li>\n\n\n\n<li>Braza 25 yardas<\/li>\n\n\n\n<li>Mariposa 25 yardas<\/li>\n\n\n\n<li>Viraje de volteo de crol<\/li>\n<\/ol>\n\n<p><\/p>\n","protected":false},"featured_media":6097,"template":"","meta":{"_acf_changed":false},"class_list":["post-7053","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/program\/7053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":3,"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/program\/7053\/revisions"}],"predecessor-version":[{"id":8912,"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/program\/7053\/revisions\/8912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/media\/6097"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/glendale-burbank\/es\/wp-json\/wp\/v2\/media?parent=7053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}