{"id":7062,"date":"2025-07-21T23:02:24","date_gmt":"2025-07-21T23:02:24","guid":{"rendered":"https:\/\/britishswimschool.com\/alamitosbay-loscerritos\/program\/delfin\/"},"modified":"2026-09-02T02:01:10","modified_gmt":"2026-09-02T02:01:10","slug":"delfin","status":"publish","type":"program","link":"https:\/\/britishswimschool.com\/alamitosbay-loscerritos\/es\/programs\/delfin\/","title":{"rendered":"Dolphin"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7062\" class=\"elementor elementor-7062 elementor-5892\" data-elementor-post-type=\"program\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1dd9cb32 e-flex e-con-boxed e-con e-parent\" data-id=\"1dd9cb32\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21f601ad elementor-widget elementor-widget-text-editor\" data-id=\"21f601ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<h3 class=\"wp-block-heading\">Para nadadores con capacidades especiales<\/h3>\n\n\n\n<p>Dolphin es nuestro programa de nataci\u00f3n adaptada, cuidadosamente dise\u00f1ado para nadadores de todas las edades con diferencias de desarrollo, sensoriales o f\u00edsicas. Los instructores reciben formaci\u00f3n especializada centrada en la empat\u00eda, el desarrollo infantil y las t\u00e9cnicas de nataci\u00f3n adaptada para garantizar que cada nadador reciba el apoyo que necesita. Cada clase se adapta al individuo, encontr\u00e1ndose con \u00e9l donde est\u00e1 y aprovechando sus puntos fuertes \u00fanicos. Con un enfoque en la comodidad, la comunicaci\u00f3n y la seguridad acu\u00e1tica fundamental, este programa proporciona un entorno acogedor y comprensivo donde cada nadador puede aprender y prosperar a su propio ritmo.   <\/p>\n\n\n\n<p>Las proporciones de instructor por alumno var\u00edan en funci\u00f3n de las necesidades individuales de cada nadador para garantizar el entorno de aprendizaje m\u00e1s seguro y de mayor apoyo.<\/p>\n\n\n\n<p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":6072,"template":"","meta":{"_acf_changed":false},"class_list":["post-7062","program","type-program","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/britishswimschool.com\/alamitosbay-loscerritos\/es\/wp-json\/wp\/v2\/program\/7062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/britishswimschool.com\/alamitosbay-loscerritos\/es\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/britishswimschool.com\/alamitosbay-loscerritos\/es\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":4,"href":"https:\/\/britishswimschool.com\/alamitosbay-loscerritos\/es\/wp-json\/wp\/v2\/program\/7062\/revisions"}],"predecessor-version":[{"id":9098,"href":"https:\/\/britishswimschool.com\/alamitosbay-loscerritos\/es\/wp-json\/wp\/v2\/program\/7062\/revisions\/9098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/britishswimschool.com\/alamitosbay-loscerritos\/es\/wp-json\/wp\/v2\/media\/6072"}],"wp:attachment":[{"href":"https:\/\/britishswimschool.com\/alamitosbay-loscerritos\/es\/wp-json\/wp\/v2\/media?parent=7062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}